{"id":3,"count":1,"description":"","link":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/","name":"Cidades","slug":"cidades","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Cidades - Minas em Foco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Cidades - Minas em Foco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Minas em Foco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/category\\\/cidades\\\/\",\"url\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/category\\\/cidades\\\/\",\"name\":\"Arquivo de Cidades - Minas em Foco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/category\\\/cidades\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/category\\\/cidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/\",\"name\":\"Minas em Foco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#organization\",\"name\":\"Minas em Foco\",\"url\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo1.png\",\"contentUrl\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo1.png\",\"width\":1236,\"height\":461,\"caption\":\"Minas em Foco\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minasemfoco.com.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Cidades - Minas em Foco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Cidades - Minas em Foco","og_url":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/","og_site_name":"Minas em Foco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/","url":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/","name":"Arquivo de Cidades - Minas em Foco","isPartOf":{"@id":"https:\/\/www.minasemfoco.com.br\/portal\/#website"},"breadcrumb":{"@id":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minasemfoco.com.br\/portal\/category\/cidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.minasemfoco.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Cidades"}]},{"@type":"WebSite","@id":"https:\/\/www.minasemfoco.com.br\/portal\/#website","url":"https:\/\/www.minasemfoco.com.br\/portal\/","name":"Minas em Foco","description":"","publisher":{"@id":"https:\/\/www.minasemfoco.com.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minasemfoco.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.minasemfoco.com.br\/portal\/#organization","name":"Minas em Foco","url":"https:\/\/www.minasemfoco.com.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.minasemfoco.com.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.minasemfoco.com.br\/portal\/wp-content\/uploads\/2026\/04\/logo1.png","contentUrl":"https:\/\/www.minasemfoco.com.br\/portal\/wp-content\/uploads\/2026\/04\/logo1.png","width":1236,"height":461,"caption":"Minas em Foco"},"image":{"@id":"https:\/\/www.minasemfoco.com.br\/portal\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.minasemfoco.com.br\/portal\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minasemfoco.com.br\/portal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.minasemfoco.com.br\/portal\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.minasemfoco.com.br\/portal\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}